{"id":17935,"date":"2023-11-29T23:44:52","date_gmt":"2023-11-30T04:44:52","guid":{"rendered":"https:\/\/www.aiacanada.com\/?page_id=17935"},"modified":"2023-12-06T14:54:20","modified_gmt":"2023-12-06T19:54:20","slug":"participez-en-tant-quorateur-ou-oratrice-a-la-journee-de-laia-canada-dans-les-cfp-au-quebec","status":"publish","type":"page","link":"https:\/\/www.aiacanada.com\/fr\/participez-en-tant-quorateur-ou-oratrice-a-la-journee-de-laia-canada-dans-les-cfp-au-quebec\/","title":{"rendered":"Participez en tant qu\u2019orateur ou oratrice \u00e0 la Journ\u00e9e de l\u2019AIA Canada dans les CFP au Qu\u00e9bec"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"17935\" class=\"elementor elementor-17935\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-93ff533 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"93ff533\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d6e069\" data-id=\"6d6e069\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-faaa363 elementor-widget elementor-widget-text-editor\" data-id=\"faaa363\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>La division du Qu\u00e9bec de l\u2019AIA Canada a pris l\u2019initiative en 2022 de relancer les activit\u00e9s de la foire aux stages dans les centres de formation professionnelle (CFP) dans le cadre de leur dossier de la rel\u00e8ve.&nbsp;<\/p>\n<p>L\u2019\u00e9v\u00e9nement \u00ab&nbsp;Journ\u00e9e de l\u2019AIA Canada&nbsp;\u00bb a \u00e9t\u00e9 cr\u00e9\u00e9 dans le but de faire conna\u00eetre l\u2019AIA Canada et le secteur de l\u2019entretien et de la r\u00e9paration automobile aux \u00e9tudiants en m\u00e9canique automobile et en carrosserie des centres de formation professionnelle (CFP), afin de les informer sur cette industrie et sur les excellentes possibilit\u00e9s de carri\u00e8re qui s\u2019offrent \u00e0 eux.&nbsp;&nbsp;<\/p>\n<p>Nous sommes \u00e0 la recherche de professionnels et professionnelles en m\u00e9canique automobile et\/ou en carrosserie au Qu\u00e9bec qui pourraient se joindre \u00e0 nous dans les CFP afin de t\u00e9moigner de votre parcours dans l\u2019industrie, de partager vos connaissances et de discuter des opportunit\u00e9s qui s\u2019offrent \u00e0 cette nouvelle g\u00e9n\u00e9ration dans l\u2019industrie.<\/p>\n<p>La date d\u2019\u00e9ch\u00e9ance pour soumettre une demande de participation est le 19 janvier 2024.<\/p>\n<p>Veuillez noter que toute demande de participation sont soumises \u00e0 l\u2019approbation de l\u2019AIA Canada. <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-374d62a elementor-widget elementor-widget-heading\" data-id=\"374d62a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Renseignements sur l\u2019\u00e9v\u00e9nement<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0832a3a elementor-widget elementor-widget-text-editor\" data-id=\"0832a3a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Date<\/strong><\/p><p>Le mardi 20 f\u00e9vrier 2024<\/p><p><strong>Lieu<\/strong><\/p><p>Plusieurs centres de formation professionnelles au Qu\u00e9bec<\/p><p><strong>Horaire<\/strong><\/p><p>Varie selon les centres de formation professionnelles au Qu\u00e9bec participants<\/p><p><strong>Comment vous pouvez contribuer ?<\/strong><\/p><p>Nous recherchons des professionnels passionn\u00e9s par le partage d&rsquo;exp\u00e9riences professionnelles significatives. En vous inscrivant comme volontaire, vous aurez l&rsquo;occasion de :<\/p><ul><li>Partager votre histoire : Racontez votre parcours professionnel, les le\u00e7ons que vous avez apprises, et les moments qui ont fa\u00e7onn\u00e9 votre carri\u00e8re.<\/li><li>Inspirer les jeunes \u00e9tudiants : Votre exp\u00e9rience peut \u00eatre la source d&rsquo;inspiration qui motive quelqu&rsquo;un \u00e0 pers\u00e9v\u00e9rer malgr\u00e9 les d\u00e9fis.<\/li><\/ul><p><strong>Comment rejoindre notre \u00e9quipe de b\u00e9n\u00e9voles <\/strong><strong>?<\/strong><\/p><p>C&rsquo;est simple! Remplissez le formulaire d&rsquo;inscription ci-dessous et rejoignez-nous dans cette mission enrichissante. Nous avons h\u00e2te de vous accueillir dans cette journ\u00e9e pour la rel\u00e8ve. Ensemble, faisons de chaque exp\u00e9rience professionnelle une source d&rsquo;inspiration pour la prochaine g\u00e9n\u00e9ration de travailleurs!<\/p><p>Un repr\u00e9sentant ou une repr\u00e9sentante de l\u2019AIA Canada vous contactera suite au d\u00e9p\u00f4t de votre demande afin de vous faire part du statut de votre demande et des d\u00e9tails concernant l\u2019\u00e9v\u00e9nement (lieu et heure exacte, etc.) et votre implication. Il ou elle vous communiquera une liste des CFP participants et des plages horaires disponibles afin de confirmer votre participation.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d2425f elementor-widget elementor-widget-heading\" data-id=\"0d2425f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Posez votre demande de participation en tant qu\u2019orateur ou oratrice<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91ff0df elementor-widget elementor-widget-shortcode\" data-id=\"91ff0df\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La division du Qu\u00e9bec de l\u2019AIA Canada a pris l\u2019initiative en 2022 de relancer les activit\u00e9s de la foire aux stages dans les centres de formation professionnelle (CFP) dans le cadre de leur dossier de la rel\u00e8ve.&nbsp; L\u2019\u00e9v\u00e9nement \u00ab&nbsp;Journ\u00e9e de l\u2019AIA Canada&nbsp;\u00bb a \u00e9t\u00e9 cr\u00e9\u00e9 dans le but de faire conna\u00eetre l\u2019AIA Canada et le [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-17935","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"wpml_current_locale":"fr_CA","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/www.aiacanada.com\/fr\/wp-json\/wp\/v2\/pages\/17935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aiacanada.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.aiacanada.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.aiacanada.com\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aiacanada.com\/fr\/wp-json\/wp\/v2\/comments?post=17935"}],"version-history":[{"count":0,"href":"https:\/\/www.aiacanada.com\/fr\/wp-json\/wp\/v2\/pages\/17935\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aiacanada.com\/fr\/wp-json\/wp\/v2\/media?parent=17935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}